{"id":16760,"date":"2017-07-29T21:42:53","date_gmt":"2017-07-29T21:42:53","guid":{"rendered":"https:\/\/www.egirassol.com.br\/home\/wp-content\/uploads\/2017\/07\/20170728_171411_Film3.jpg"},"modified":"2017-07-29T21:42:53","modified_gmt":"2017-07-29T21:42:53","slug":"20170728_171411_film3","status":"inherit","type":"attachment","link":"https:\/\/www.egirassol.com.br\/home\/20170728_171411_film3\/","title":{"rendered":"20170728_171411_Film3"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-16760","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.egirassol.com.br\/home\/wp-content\/uploads\/2017\/07\/20170728_171411_Film3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.egirassol.com.br\/home\/wp-content\/uploads\/2017\/07\/20170728_171411_Film3-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.egirassol.com.br\/home\/wp-content\/uploads\/2017\/07\/20170728_171411_Film3-300x200.jpg 300w, https:\/\/www.egirassol.com.br\/home\/wp-content\/uploads\/2017\/07\/20170728_171411_Film3-768x512.jpg 768w, https:\/\/www.egirassol.com.br\/home\/wp-content\/uploads\/2017\/07\/20170728_171411_Film3.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":900,"height":600,"file":"2017\/07\/20170728_171411_Film3.jpg","sizes":{"thumbnail":{"file":"20170728_171411_Film3-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.egirassol.com.br\/home\/wp-content\/uploads\/2017\/07\/20170728_171411_Film3-150x150.jpg"},"medium":{"file":"20170728_171411_Film3-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.egirassol.com.br\/home\/wp-content\/uploads\/2017\/07\/20170728_171411_Film3-300x200.jpg"},"medium_large":{"file":"20170728_171411_Film3-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.egirassol.com.br\/home\/wp-content\/uploads\/2017\/07\/20170728_171411_Film3-768x512.jpg"},"post-thumbnail":{"file":"20170728_171411_Film3-900x500.jpg","width":900,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.egirassol.com.br\/home\/wp-content\/uploads\/2017\/07\/20170728_171411_Film3-900x500.jpg"},"full":{"file":"20170728_171411_Film3.jpg","width":900,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.egirassol.com.br\/home\/wp-content\/uploads\/2017\/07\/20170728_171411_Film3.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"LG-K220","caption":"","created_timestamp":"1501262051","copyright":"","focal_length":"3.62","iso":"50","shutter_speed":"0.016665","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.egirassol.com.br\/home\/wp-content\/uploads\/2017\/07\/20170728_171411_Film3.jpg","_links":{"self":[{"href":"https:\/\/www.egirassol.com.br\/home\/wp-json\/wp\/v2\/media\/16760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.egirassol.com.br\/home\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.egirassol.com.br\/home\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.egirassol.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.egirassol.com.br\/home\/wp-json\/wp\/v2\/comments?post=16760"}]}}